{"id":696,"date":"2020-09-01T08:22:53","date_gmt":"2020-09-01T06:22:53","guid":{"rendered":"https:\/\/festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2020\/09\/118300428_3287603704629157_5482513783776601080_n.jpg"},"modified":"2020-09-01T08:22:53","modified_gmt":"2020-09-01T06:22:53","slug":"118300428_3287603704629157_5482513783776601080_n","status":"inherit","type":"attachment","link":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/118300428_3287603704629157_5482513783776601080_n\/","title":{"rendered":"118300428_3287603704629157_5482513783776601080_n"},"author":2,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"smush":{"stats":{"percent":4.8630877268431805,"bytes":8594,"size_before":176719,"size_after":168125,"time":0.43000000000000005,"api_version":"1.0","lossy":false,"keep_exif":0},"sizes":{"medium":{"percent":6.44,"bytes":1983,"size_before":30775,"size_after":28792,"time":0.14},"thumbnail":{"percent":8.48,"bytes":830,"size_before":9790,"size_after":8960,"time":0.13},"medium_large":{"percent":4.25,"bytes":5781,"size_before":136154,"size_after":130373,"time":0.16}}},"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2020\/09\/118300428_3287603704629157_5482513783776601080_n.jpg'><img width=\"300\" height=\"300\" src=\"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2020\/09\/118300428_3287603704629157_5482513783776601080_n-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2020\/09\/118300428_3287603704629157_5482513783776601080_n-300x300.jpg 300w, http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2020\/09\/118300428_3287603704629157_5482513783776601080_n-150x150.jpg 150w, http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2020\/09\/118300428_3287603704629157_5482513783776601080_n-768x768.jpg 768w, http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2020\/09\/118300428_3287603704629157_5482513783776601080_n.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":960,"height":960,"file":"2020\/09\/118300428_3287603704629157_5482513783776601080_n.jpg","sizes":{"medium":{"file":"118300428_3287603704629157_5482513783776601080_n-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2020\/09\/118300428_3287603704629157_5482513783776601080_n-300x300.jpg"},"thumbnail":{"file":"118300428_3287603704629157_5482513783776601080_n-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2020\/09\/118300428_3287603704629157_5482513783776601080_n-150x150.jpg"},"medium_large":{"file":"118300428_3287603704629157_5482513783776601080_n-768x768.jpg","width":768,"height":768,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2020\/09\/118300428_3287603704629157_5482513783776601080_n-768x768.jpg"},"full":{"file":"118300428_3287603704629157_5482513783776601080_n.jpg","width":960,"height":960,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2020\/09\/118300428_3287603704629157_5482513783776601080_n.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0"}},"post":null,"source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2020\/09\/118300428_3287603704629157_5482513783776601080_n.jpg","_links":{"self":[{"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/media\/696"}],"collection":[{"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/comments?post=696"}]}}