{"id":280,"date":"2020-07-22T11:07:28","date_gmt":"2020-07-22T09:07:28","guid":{"rendered":"https:\/\/festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_9340.jpg"},"modified":"2020-07-22T11:07:28","modified_gmt":"2020-07-22T09:07:28","slug":"dsc_9340","status":"inherit","type":"attachment","link":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/dsc_9340\/","title":{"rendered":"DSC_9340"},"author":2,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"smush":{"stats":{"percent":6.58871914577298,"bytes":9484,"size_before":143943,"size_after":134459,"time":0.08,"api_version":"1.0","lossy":false,"keep_exif":0},"sizes":{"medium":{"percent":7.68,"bytes":1837,"size_before":23922,"size_after":22085,"time":0.02},"thumbnail":{"percent":8.26,"bytes":876,"size_before":10609,"size_after":9733,"time":0.01},"medium_large":{"percent":6.19,"bytes":6771,"size_before":109412,"size_after":102641,"time":0.05}}},"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_9340.jpg'><img width=\"300\" height=\"200\" src=\"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_9340-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_9340-300x200.jpg 300w, http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_9340-768x512.jpg 768w, http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_9340.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":667,"file":"2019\/12\/DSC_9340.jpg","sizes":{"medium":{"file":"DSC_9340-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_9340-300x200.jpg"},"thumbnail":{"file":"DSC_9340-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_9340-150x150.jpg"},"medium_large":{"file":"DSC_9340-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_9340-768x512.jpg"},"full":{"file":"DSC_9340.jpg","width":1000,"height":667,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_9340.jpg"}},"image_meta":{"aperture":"3.5","credit":"","camera":"NIKON D7100","caption":"","created_timestamp":"1535217634","copyright":"","focal_length":"112","iso":"1250","shutter_speed":"0.003125","title":"","orientation":"0"}},"post":null,"source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_9340.jpg","_links":{"self":[{"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/media\/280"}],"collection":[{"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/comments?post=280"}]}}