{"id":277,"date":"2020-07-22T11:07:17","date_gmt":"2020-07-22T09:07:17","guid":{"rendered":"https:\/\/festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_8550.jpg"},"modified":"2020-07-22T11:07:17","modified_gmt":"2020-07-22T09:07:17","slug":"dsc_8550","status":"inherit","type":"attachment","link":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/dsc_8550\/","title":{"rendered":"DSC_8550"},"author":2,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"smush":{"stats":{"percent":7.097270656349434,"bytes":11621,"size_before":163739,"size_after":152118,"time":0.12000000000000001,"api_version":"1.0","lossy":false,"keep_exif":0},"sizes":{"medium":{"percent":8.23,"bytes":2091,"size_before":25413,"size_after":23322,"time":0.07},"thumbnail":{"percent":8.25,"bytes":868,"size_before":10521,"size_after":9653,"time":0.02},"medium_large":{"percent":6.78,"bytes":8662,"size_before":127805,"size_after":119143,"time":0.03}}},"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_8550.jpg'><img width=\"300\" height=\"200\" src=\"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_8550-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_8550-300x200.jpg 300w, http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_8550-768x512.jpg 768w, http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_8550.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":667,"file":"2019\/12\/DSC_8550.jpg","sizes":{"medium":{"file":"DSC_8550-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_8550-300x200.jpg"},"thumbnail":{"file":"DSC_8550-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_8550-150x150.jpg"},"medium_large":{"file":"DSC_8550-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_8550-768x512.jpg"},"full":{"file":"DSC_8550.jpg","width":1000,"height":667,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_8550.jpg"}},"image_meta":{"aperture":"3.5","credit":"","camera":"NIKON D7100","caption":"","created_timestamp":"1535038998","copyright":"","focal_length":"17","iso":"500","shutter_speed":"0.00025","title":"","orientation":"1"}},"post":null,"source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_8550.jpg","_links":{"self":[{"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/media\/277"}],"collection":[{"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/comments?post=277"}]}}