{"id":266,"date":"2020-07-22T11:06:18","date_gmt":"2020-07-22T09:06:18","guid":{"rendered":"https:\/\/festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4882.jpg"},"modified":"2020-07-22T11:06:18","modified_gmt":"2020-07-22T09:06:18","slug":"dsc_4882","status":"inherit","type":"attachment","link":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/dsc_4882\/","title":{"rendered":"DSC_4882"},"author":2,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"smush":{"stats":{"percent":4.985134974432156,"bytes":6288,"size_before":126135,"size_after":119847,"time":0.21,"api_version":"1.0","lossy":false,"keep_exif":0},"sizes":{"medium":{"percent":6.19,"bytes":1258,"size_before":20338,"size_after":19080,"time":0.11},"thumbnail":{"percent":6.74,"bytes":569,"size_before":8442,"size_after":7873,"time":0.04},"medium_large":{"percent":4.58,"bytes":4461,"size_before":97355,"size_after":92894,"time":0.06}}},"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4882.jpg'><img width=\"300\" height=\"200\" src=\"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4882-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4882-300x200.jpg 300w, http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4882-768x512.jpg 768w, http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4882.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":667,"file":"2019\/12\/DSC_4882.jpg","sizes":{"medium":{"file":"DSC_4882-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4882-300x200.jpg"},"thumbnail":{"file":"DSC_4882-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4882-150x150.jpg"},"medium_large":{"file":"DSC_4882-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4882-768x512.jpg"},"full":{"file":"DSC_4882.jpg","width":1000,"height":667,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4882.jpg"}},"image_meta":{"aperture":"3.2","credit":"","camera":"NIKON D7200","caption":"","created_timestamp":"1535137432","copyright":"","focal_length":"40","iso":"1250","shutter_speed":"0.0025","title":"","orientation":"0"}},"post":null,"source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4882.jpg","_links":{"self":[{"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/media\/266"}],"collection":[{"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/comments?post=266"}]}}