{"id":265,"date":"2020-07-22T11:06:14","date_gmt":"2020-07-22T09:06:14","guid":{"rendered":"https:\/\/festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4637.jpg"},"modified":"2020-07-22T11:06:14","modified_gmt":"2020-07-22T09:06:14","slug":"dsc_4637","status":"inherit","type":"attachment","link":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/dsc_4637\/","title":{"rendered":"DSC_4637"},"author":2,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"smush":{"stats":{"percent":5.752025125665451,"bytes":7747,"size_before":134683,"size_after":126936,"time":0.2,"api_version":"1.0","lossy":false,"keep_exif":0},"sizes":{"medium":{"percent":6.75,"bytes":1441,"size_before":21341,"size_after":19900,"time":0.11},"thumbnail":{"percent":7.39,"bytes":706,"size_before":9548,"size_after":8842,"time":0.04},"medium_large":{"percent":5.4,"bytes":5600,"size_before":103794,"size_after":98194,"time":0.05}}},"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4637.jpg'><img width=\"300\" height=\"200\" src=\"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4637-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4637-300x200.jpg 300w, http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4637-768x512.jpg 768w, http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4637.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":667,"file":"2019\/12\/DSC_4637.jpg","sizes":{"medium":{"file":"DSC_4637-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4637-300x200.jpg"},"thumbnail":{"file":"DSC_4637-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4637-150x150.jpg"},"medium_large":{"file":"DSC_4637-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4637-768x512.jpg"},"full":{"file":"DSC_4637.jpg","width":1000,"height":667,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4637.jpg"}},"image_meta":{"aperture":"3.2","credit":"","camera":"NIKON D7200","caption":"","created_timestamp":"1535061996","copyright":"","focal_length":"24","iso":"1250","shutter_speed":"0.003125","title":"","orientation":"0"}},"post":null,"source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_4637.jpg","_links":{"self":[{"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/media\/265"}],"collection":[{"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/comments?post=265"}]}}