{"id":264,"date":"2020-07-22T11:06:11","date_gmt":"2020-07-22T09:06:11","guid":{"rendered":"https:\/\/festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_3652.jpg"},"modified":"2020-07-22T11:06:11","modified_gmt":"2020-07-22T09:06:11","slug":"dsc_3652","status":"inherit","type":"attachment","link":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/dsc_3652\/","title":{"rendered":"DSC_3652"},"author":2,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"smush":{"stats":{"percent":4.074954050298113,"bytes":4545,"size_before":111535,"size_after":106990,"time":0.29,"api_version":"1.0","lossy":false,"keep_exif":0},"sizes":{"medium":{"percent":5.35,"bytes":993,"size_before":18574,"size_after":17581,"time":0.01},"thumbnail":{"percent":5.81,"bytes":480,"size_before":8261,"size_after":7781,"time":0.06},"medium_large":{"percent":3.63,"bytes":3072,"size_before":84700,"size_after":81628,"time":0.22}}},"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_3652.jpg'><img width=\"300\" height=\"200\" src=\"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_3652-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_3652-300x200.jpg 300w, http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_3652-768x512.jpg 768w, http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_3652.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":667,"file":"2019\/12\/DSC_3652.jpg","sizes":{"medium":{"file":"DSC_3652-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_3652-300x200.jpg"},"thumbnail":{"file":"DSC_3652-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_3652-150x150.jpg"},"medium_large":{"file":"DSC_3652-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_3652-768x512.jpg"},"full":{"file":"DSC_3652.jpg","width":1000,"height":667,"mime_type":"image\/jpeg","source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_3652.jpg"}},"image_meta":{"aperture":"3.5","credit":"","camera":"NIKON D7200","caption":"","created_timestamp":"1534882749","copyright":"","focal_length":"38","iso":"1250","shutter_speed":"0.003125","title":"","orientation":"1"}},"post":null,"source_url":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-content\/uploads\/sites\/13\/2019\/12\/DSC_3652.jpg","_links":{"self":[{"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/media\/264"}],"collection":[{"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/archiwum.festiwale.zakopane.pl\/festiwal-folkloru\/wp-json\/wp\/v2\/comments?post=264"}]}}